{"id":20915,"date":"2024-05-30T21:19:10","date_gmt":"2024-05-31T01:19:10","guid":{"rendered":"https:\/\/montclair.wordcamp.org\/2024\/?p=20915"},"modified":"2024-05-30T22:11:51","modified_gmt":"2024-05-31T02:11:51","slug":"thank-you-bronze-sponsors","status":"publish","type":"post","link":"https:\/\/montclair.wordcamp.org\/2024\/thank-you-bronze-sponsors\/","title":{"rendered":"Thank you, BRONZE SPONSORS!"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped is-style-rectangular wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/www.bigscoots.com\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" data-id=\"485\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark-1024x256.png\" alt=\"Big scouts logo\" class=\"wp-image-485\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark-1024x256.png 1024w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark-300x75.png 300w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark-768x192.png 768w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark-500x125.png 500w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/BigScoots-logo-dark.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/freshysites.com\/wordpress\/hosting\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"230\" data-id=\"373\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/Freshy-logo.png\" alt=\"Freshy logo\" class=\"wp-image-373\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/Freshy-logo.png 784w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/Freshy-logo-300x88.png 300w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/Freshy-logo-768x225.png 768w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/Freshy-logo-500x147.png 500w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/kinsta.com\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"259\" data-id=\"578\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-1024x259.png\" alt=\"Kinsta logo\" class=\"wp-image-578\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-1024x259.png 1024w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-300x76.png 300w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-768x195.png 768w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-500x127.png 500w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-1536x389.png 1536w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-2048x519.png 2048w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-1200x304.png 1200w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/03\/Kinsta_black-1980x502.png 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.secretstache.com\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"92\" data-id=\"493\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/Secret-Stache.png\" alt=\"Secret Stache logo\" class=\"wp-image-493\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/Secret-Stache.png 500w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/02\/Secret-Stache-300x55.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.seopress.org\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"71\" data-id=\"282\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2023\/12\/seopress-logo-svg.png\" alt=\"SEO Press logo\" class=\"wp-image-282\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2023\/12\/seopress-logo-svg.png 400w, https:\/\/montclair.wordcamp.org\/2024\/files\/2023\/12\/seopress-logo-svg-300x53.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/seravo.com\/en\/\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"759\" data-id=\"374\" src=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/seravo_logo.png\" alt=\"Seravo logo\" class=\"wp-image-374\" srcset=\"https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/seravo_logo.png 1024w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/seravo_logo-300x222.png 300w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/seravo_logo-768x569.png 768w, https:\/\/montclair.wordcamp.org\/2024\/files\/2024\/01\/seravo_logo-405x300.png 405w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":20154767,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-20915","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfcD7g-5rl","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/posts\/20915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/users\/20154767"}],"replies":[{"embeddable":true,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/comments?post=20915"}],"version-history":[{"count":23,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/posts\/20915\/revisions"}],"predecessor-version":[{"id":20934,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/posts\/20915\/revisions\/20934"}],"wp:attachment":[{"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/media?parent=20915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/categories?post=20915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montclair.wordcamp.org\/2024\/wp-json\/wp\/v2\/tags?post=20915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}